{"id":24514,"date":"2021-07-07T10:27:08","date_gmt":"2021-07-07T08:27:08","guid":{"rendered":"https:\/\/abd.ong\/?p=24514"},"modified":"2021-07-27T10:49:31","modified_gmt":"2021-07-27T08:49:31","slug":"abd-participa-al-iii-congres-de-laccio-social","status":"publish","type":"post","link":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/","title":{"rendered":"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">D\u2019una banda, s&#8217;ha presentat el projecte de<em> Noves formes de cura col\u00b7lectiva<\/em> i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen amb el VIH\/sida en situaci\u00f3 d\u2019exclusi\u00f3 social en el context de la COVID-19<\/h4>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>L&#8217;<a href=\"https:\/\/abd.ong\/ca\/\">Associaci\u00f3 Benestar i Desenvolupament ABD<\/a> ha estat present al <a href=\"https:\/\/inclusio.cat\/\">III Congr\u00e9s de l\u2019Acci\u00f3 Social<\/a> que s&#8217;ha celebrat els dies 8 i 9 de juliol. I ha estat per partida doble. D\u2019una banda, s&#8217;ha presentat el projecte de <em>Noves formes de cura col\u00b7lectiva<\/em> i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen amb el VIH\/sida en situaci\u00f3 d\u2019exclusi\u00f3 social en el context de la COVID-19.<\/p>\n\n<p>El Congr\u00e9s de l\u2019Acci\u00f3 Social \u2013 Inclusi\u00f3.cat \u00e9s un esdeveniment adre\u00e7at a tots els agents del Sistema Catal\u00e0 de Serveis Socials que, sumant-se a altres congressos del sector, vol <strong>incentivar la creaci\u00f3 de coneixement basat en l\u2019evid\u00e8ncia, per enfortir les disciplines acad\u00e8miques i professionals en l\u2019\u00e0mbit dels serveis socials<\/strong>.<\/p>\n\n<p>El Congr\u00e9s l\u2019organitzen el <a href=\"https:\/\/treballiaferssocials.gencat.cat\/ca\/inici\">Departament de Drets Socials de la Generalitat de Catalunya<\/a> i la <a href=\"https:\/\/www.uvic.cat\/recerca\/catedra-serveis-socials\">C\u00e0tedra de Serveis Socials de la Universitat de Vic \u2013 Universitat Central de Catalunya<\/a>.<\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h4 class=\"wp-block-heading\"><strong>Noves formes de cura col\u00b7lectiva<\/strong><\/h4>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Des de 2013, l&#8217;Associaci\u00f3 Benestar i Desenvolupament ha posat en marxa diferents <a href=\"https:\/\/www.youtube.com\/watch?v=cMfkg8gal9A\">\u2018Espais grupals de cures col\u00b7lectives\u2019,<\/a> alguns dins de serveis concrets i altres oberts i comunitaris que s\u00f3n un servei en si.<\/p>\n\n<p>S\u00f3n espais grupals, d&#8217;acc\u00e9s lliure i gratu\u00eft, en ells tenen cabuda persones de totes les edats i totes les caracter\u00edstiques socioculturals. Les sessions mantenen la mateixa estructura (freq\u00fc\u00e8ncia setmanal, 1,5 hores de durada i obert durant tot l&#8217;any, a causa de les restriccions per la COVID-19 actualment es realitza en format online). Estan condu\u00efts per dos professionals.<\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"437\" height=\"589\" src=\"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/Captura-10.jpg\" alt=\"\" class=\"wp-image-24894\" srcset=\"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/Captura-10.jpg 437w, https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/Captura-10-223x300.jpg 223w\" sizes=\"(max-width: 437px) 100vw, 437px\" \/><\/figure><\/div>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><strong>S\u00f3n espais de participaci\u00f3, reflexi\u00f3, decisi\u00f3 i apoderament col\u00b7lectiu<\/strong>, les persones facilitadores mantenen un rol horitzontal aportant una m\u00ednima estructura i cura, s\u00f3n els i les participants, ve\u00efns i ve\u00efnes les que decideixen que continguts tractar i com. \u00c9s un espai lliure i autogestionat.<\/p>\n\n<p>L&#8217;espai de trobada i participaci\u00f3 <strong>funciona com un laboratori natural que demostra que les persones no estan soles, que formen part d&#8217;un entorn, d&#8217;una xarxa m\u00e9s \u00e0mplia de relaci\u00f3 i cura<\/strong>. Els seus objectius s\u00f3n millorar el malestar emocional, combatre la soledat i facilitar l\u00b4intercanvi d&#8217;experi\u00e8ncies.<\/p>\n\n<p>La presentaci\u00f3 ha anat a c\u00e0rrec de <strong>Carolina Torralbo<\/strong>, coordinadora dels grups de participaci\u00f3 comunit\u00e0ria de l\u2019<a href=\"https:\/\/abd.ong\/ca\/causes\/infancia-i-familia\/\">\u00c0rea d\u2019Inf\u00e0ncia i Fam\u00edlia d\u2019ABD<\/a>.<\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h4 class=\"wp-block-heading\"><strong>Atenci\u00f3 i acompanyament a les persones que viuen amb el VIH\/sida<\/strong><\/h4>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Per un altre costat, s&#8217;han presentat els resultats de la tasca duta per part de les entitats catalanes que treballen en l\u2019atenci\u00f3 i acompanyament a les persones que viuen amb el VIH\/sida en situaci\u00f3 d\u2019exclusi\u00f3 social en el context de la COVID-19.<\/p>\n\n<p>En concret s&#8217;han mostrat els resultats del treball de la Comissi\u00f3 de VIH\/SIDA i exclusi\u00f3 social de la <a href=\"https:\/\/acciosocial.org\/\">federaci\u00f3 d\u2019Entitats Catalanes d\u2019Acci\u00f3 Social ECAS<\/a>, que est\u00e0 <a href=\"https:\/\/abd.ong\/ca\/desigualtat\/aldana-menendez-nova-coordinadora-de-la-comissio-vih-sida-decas\/\">coordinada per <strong>Aldana Men\u00e9ndez<\/strong><\/a>, responsable dels programes de Salut Sexual i VIH de l\u2019Associaci\u00f3 Benestar i Desenvolupament.<\/p>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"416\" height=\"580\" src=\"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/Captura-27.jpg\" alt=\"\" class=\"wp-image-24891\" srcset=\"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/Captura-27.jpg 416w, https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/Captura-27-215x300.jpg 215w\" sizes=\"(max-width: 416px) 100vw, 416px\" \/><\/figure><\/div>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>La Comissi\u00f3 de VIH\/SIDA i exclusi\u00f3 social d\u2019ECAS est\u00e0 formada per 11 entitats que gestionen recursos residencials, tant centres residencials com pisos de suport, i tamb\u00e9 el Servei d\u2019Acompanyament a la Vida Aut\u00f2noma (SAVA) a Catalunya. La Comissi\u00f3 representa <strong>un espai de construcci\u00f3 col\u00b7lectiva, de reflexi\u00f3 i di\u00e0leg que promou una visi\u00f3 cr\u00edtica en relaci\u00f3 als models d\u2019intervenci\u00f3<\/strong>, la detecci\u00f3 de les necessitats emergents i l\u2019elaboraci\u00f3 de respostes creatives davant les problem\u00e0tiques que ens imposa el context en el qual estem immerses.<\/p>\n\n<p>La presentaci\u00f3 ha anat a c\u00e0rrec de <strong>Josep Maria Lluch<\/strong>, de <a href=\"https:\/\/www.acollida.org\/\">Fundaci\u00f3 Acollida i Esperan\u00e7a<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u2019una banda, s&#8217;ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen amb el VIH\/sida en situaci\u00f3&hellip;<\/p>\n","protected":false},"author":2,"featured_media":24505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1299,66,1303],"tags":[1845,2458,2462,2460,2461,2457,227,2459,2287,624,2456,322],"class_list":["post-24514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desigualtat","category-general-ca","category-infancia-i-familia","tag-accio-social","tag-accio-social-ca","tag-accio-social-i-abd","tag-comissio-vih-sida","tag-congres-de-laccio-social","tag-cura-collectiva","tag-ecas","tag-ecas-ca","tag-exclusio-social-ca-2","tag-exclusio-social","tag-serveis-socials-ca","tag-serveis-socials"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social - ABD<\/title>\n<meta name=\"description\" content=\"D\u2019una banda, s&#039;ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social - ABD\" \/>\n<meta property=\"og:description\" content=\"D\u2019una banda, s&#039;ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/\" \/>\n<meta property=\"og:site_name\" content=\"ABD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abd.ong\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T08:27:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-27T08:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/EtuE2zDXMAEnoDY.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enric Guinart\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abd_ong\" \/>\n<meta name=\"twitter:site\" content=\"@abd_ong\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enric Guinart\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/\"},\"author\":{\"name\":\"Enric Guinart\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/person\\\/d0f5fe279a7ad908de6a6d1332bfd7d8\"},\"headline\":\"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social\",\"datePublished\":\"2021-07-07T08:27:08+00:00\",\"dateModified\":\"2021-07-27T08:49:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/\"},\"wordCount\":671,\"publisher\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EtuE2zDXMAEnoDY.jpg\",\"keywords\":[\"acci\u00f3 social\",\"acci\u00f3 social\",\"acci\u00f3 social i ABD\",\"Comissi\u00f3 VIH\\\/SIDA\",\"Congr\u00e9s de l'Acci\u00f3 Social\",\"cura col\u00b7lectiva\",\"ECAS\",\"ECAS\",\"exclusi\u00f3 social\",\"exclusi\u00f3 social\",\"Serveis Socials\",\"serveis socials\"],\"articleSection\":[\"Desigualtat\",\"General\",\"Inf\u00e0ncia i fam\u00edlia\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/\",\"url\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/\",\"name\":\"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social - ABD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EtuE2zDXMAEnoDY.jpg\",\"datePublished\":\"2021-07-07T08:27:08+00:00\",\"dateModified\":\"2021-07-27T08:49:31+00:00\",\"description\":\"D\u2019una banda, s'ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EtuE2zDXMAEnoDY.jpg\",\"contentUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EtuE2zDXMAEnoDY.jpg\",\"width\":680,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/general-ca\\\/abd-participa-al-iii-congres-de-laccio-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/abd.ong\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/abd.ong\\\/ca\\\/\",\"name\":\"ABD\",\"description\":\"Asociaci\u00f3n Bienestar y Desarrollo\",\"publisher\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abd.ong\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#organization\",\"name\":\"Associaci\u00f3 Benestar i Desenvolupament\",\"alternateName\":\"ABD\",\"url\":\"https:\\\/\\\/abd.ong\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Icona.png\",\"contentUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Icona.png\",\"width\":190,\"height\":187,\"caption\":\"Associaci\u00f3 Benestar i Desenvolupament\"},\"image\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/abd.ong\",\"https:\\\/\\\/x.com\\\/abd_ong\",\"https:\\\/\\\/www.instagram.com\\\/abd_ong\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/abdong\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CANALABD\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/person\\\/d0f5fe279a7ad908de6a6d1332bfd7d8\",\"name\":\"Enric Guinart\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social - ABD","description":"D\u2019una banda, s'ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/","og_locale":"ca_ES","og_type":"article","og_title":"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social - ABD","og_description":"D\u2019una banda, s'ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen","og_url":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/","og_site_name":"ABD","article_publisher":"https:\/\/www.facebook.com\/abd.ong","article_published_time":"2021-07-07T08:27:08+00:00","article_modified_time":"2021-07-27T08:49:31+00:00","og_image":[{"width":680,"height":340,"url":"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/EtuE2zDXMAEnoDY.jpg","type":"image\/jpeg"}],"author":"Enric Guinart","twitter_card":"summary_large_image","twitter_creator":"@abd_ong","twitter_site":"@abd_ong","twitter_misc":{"Escrit per":"Enric Guinart","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#article","isPartOf":{"@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/"},"author":{"name":"Enric Guinart","@id":"https:\/\/abd.ong\/ca\/#\/schema\/person\/d0f5fe279a7ad908de6a6d1332bfd7d8"},"headline":"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social","datePublished":"2021-07-07T08:27:08+00:00","dateModified":"2021-07-27T08:49:31+00:00","mainEntityOfPage":{"@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/"},"wordCount":671,"publisher":{"@id":"https:\/\/abd.ong\/ca\/#organization"},"image":{"@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#primaryimage"},"thumbnailUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/EtuE2zDXMAEnoDY.jpg","keywords":["acci\u00f3 social","acci\u00f3 social","acci\u00f3 social i ABD","Comissi\u00f3 VIH\/SIDA","Congr\u00e9s de l'Acci\u00f3 Social","cura col\u00b7lectiva","ECAS","ECAS","exclusi\u00f3 social","exclusi\u00f3 social","Serveis Socials","serveis socials"],"articleSection":["Desigualtat","General","Inf\u00e0ncia i fam\u00edlia"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/","url":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/","name":"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social - ABD","isPartOf":{"@id":"https:\/\/abd.ong\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#primaryimage"},"image":{"@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#primaryimage"},"thumbnailUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/EtuE2zDXMAEnoDY.jpg","datePublished":"2021-07-07T08:27:08+00:00","dateModified":"2021-07-27T08:49:31+00:00","description":"D\u2019una banda, s'ha presentat el projecte de Noves formes de cura col\u00b7lectiva i, de l\u2019altra, el treball d\u2019atenci\u00f3 i acompanyament a les persones que viuen","breadcrumb":{"@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#primaryimage","url":"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/EtuE2zDXMAEnoDY.jpg","contentUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2021\/07\/EtuE2zDXMAEnoDY.jpg","width":680,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/abd.ong\/ca\/general-ca\/abd-participa-al-iii-congres-de-laccio-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/abd.ong\/ca\/"},{"@type":"ListItem","position":2,"name":"ABD participa al III Congr\u00e9s de l\u2019Acci\u00f3 Social"}]},{"@type":"WebSite","@id":"https:\/\/abd.ong\/ca\/#website","url":"https:\/\/abd.ong\/ca\/","name":"ABD","description":"Asociaci\u00f3n Bienestar y Desarrollo","publisher":{"@id":"https:\/\/abd.ong\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abd.ong\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/abd.ong\/ca\/#organization","name":"Associaci\u00f3 Benestar i Desenvolupament","alternateName":"ABD","url":"https:\/\/abd.ong\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/abd.ong\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/abd.ong\/wp-content\/uploads\/2023\/01\/Icona.png","contentUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2023\/01\/Icona.png","width":190,"height":187,"caption":"Associaci\u00f3 Benestar i Desenvolupament"},"image":{"@id":"https:\/\/abd.ong\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abd.ong","https:\/\/x.com\/abd_ong","https:\/\/www.instagram.com\/abd_ong\/","https:\/\/www.linkedin.com\/company\/abdong","https:\/\/www.youtube.com\/user\/CANALABD"]},{"@type":"Person","@id":"https:\/\/abd.ong\/ca\/#\/schema\/person\/d0f5fe279a7ad908de6a6d1332bfd7d8","name":"Enric Guinart"}]}},"_links":{"self":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts\/24514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/comments?post=24514"}],"version-history":[{"count":3,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts\/24514\/revisions"}],"predecessor-version":[{"id":24898,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts\/24514\/revisions\/24898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/media\/24505"}],"wp:attachment":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/media?parent=24514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/categories?post=24514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/tags?post=24514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}