{"id":159893,"date":"2024-04-29T13:48:30","date_gmt":"2024-04-29T11:48:30","guid":{"rendered":"https:\/\/abd.ong\/sense-categoria\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/"},"modified":"2024-04-29T13:58:30","modified_gmt":"2024-04-29T11:58:30","slug":"la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma","status":"publish","type":"post","link":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/","title":{"rendered":"La Meva Energia: L&#8217;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, <\/span><a href=\"http:\/\/abd.ong\/ca\"><span style=\"font-weight: 400;\">Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD<\/span><\/a><span style=\"font-weight: 400;\">, l\u2019<\/span><a href=\"https:\/\/ecoserveis.net\/\"><span style=\"font-weight: 400;\">Associaci\u00f3 Ecoserveis<\/span><\/a><span style=\"font-weight: 400;\"> i <\/span><a href=\"https:\/\/bitgenoma.com\/ca_ES\/page\/homepage\"><span style=\"font-weight: 400;\">BitGenoma<\/span><\/a><span style=\"font-weight: 400;\">, on ja van participar tamb\u00e9 les coordinadores dels Punts d\u2019Assessorament Energ\u00e8tic de Barcelona, s\u2019han comen\u00e7at a definir algunes de les funcionalitats que inclour\u00e0 l\u2019aplicaci\u00f3.\u00a0<\/span><\/p>\n\n<p>De moment, s\u2019est\u00e0 treballant en la part de les persones usu\u00e0ries, per definir quines necessitats ha de cobrir l\u2019aplicaci\u00f3 per donar servei tant a les persones que s\u00f3n ateses pels PAE com, en un futur, per a qualsevol persona ciutadana que vulgui ajustar i controlar el seu consum d\u2019electricitat, aigua o gas.<\/p>\n\n<p>L\u2019aplicaci\u00f3<strong> millorar\u00e0 la comunicaci\u00f3 entre les professionals del PAE i les persones usu\u00e0ries, oferir\u00e0 una informaci\u00f3 m\u00e9s concreta i actualitzada sobre l\u2019estat dels tr\u00e0mits i permetr\u00e0 a les persones que utilitzin l\u2019aplicaci\u00f3 fer una gesti\u00f3 m\u00e9s aut\u00f2noma de la seva energia<\/strong>.<\/p>\n\n<p>\u201cLa persona podr\u00e0 omplir uns q\u00fcestionaris, facilitar les seves dades i, fins i tot, demanar cita sense necessitat de posar-se en contacte amb els serveis pels canals habituals que s\u00f3n el correu electr\u00f2nic o el tel\u00e8fon d\u2019atenci\u00f3\u201d, explica Sofia Recio, coordinadora t\u00e8cnica i de drets energ\u00e8tics dels PAE. \u201cAnem en la via d\u2019obrir una altra porta d\u2019entrada a aquest servei, simplificar tota la burocr\u00e0cia de les gestions i tr\u00e0mits que implica als i les professionals per donar m\u00e9s espai a les atencions de qualitat i de cura de les persones que s\u2019adrecen al servei\u201d, afegeix.\u00a0<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\"><strong>El repte de la replicaci\u00f3<\/strong><\/h3>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><span style=\"font-weight: 400;\">Un cop dissenyada l\u2019aplicaci\u00f3 prenent la ciutat de Barcelona com a primera prova pilot, un dels reptes \u00e9s veure <strong>com es podria reproduir en una altra ciutat.\u00a0<\/strong><\/span><\/p>\n\n<p>La replicaci\u00f3 del producte a altres municipis \u201ct\u00e9 una ra\u00f3 de ser fonamentada en una necessitat\u201d, apunta el t\u00e8cnic referent de La Meva Energia per part d\u2019ABD, Marc Tejedor; que \u00e9s la manca de centralitzaci\u00f3 dels serveis d\u2019assessorament energ\u00e8tic al territori catal\u00e0. \u201c[Aquests serveis] Existeixen, depenen de cada municipi i cada municipi els ofereix de la manera que considera i utilitzant les eines que considera\u201d, afegeix. \u201cEn l\u2019\u00e0mbit local estem treballant cap a un mateix objectiu\u201d, explica, per\u00f2 amb l\u2019app web es vol intentar salvar aquesta diversitat en la gesti\u00f3 \u201cpromovent una eina que sigui \u00fatil i que es pugui aplicar a altres municipis\u201d. <\/p>\n\n<p>Aquest \u00e9s un<strong> repte complicat<\/strong>, com reconeix la desenvolupadora de BitGenoma, Michelle Lema. \u201cDonarem una eina oberta, per\u00f2 ser\u00e0 responsabilitat de cada ajuntament implementar aquest sistema i adaptar l&#8217;aplicatiu a les seves necessitats\u201d.<\/p>\n\n<p>Tot i que el desenvolupament de l\u2019aplicaci\u00f3 es troba en un estadi for\u00e7a inicial, l\u2019equip ja ha mantingut contacte amb altres entitats i projectes vigents i la valoraci\u00f3 ha estat positiva. \u201cHa generat inter\u00e8s per l\u2019app web\u201d, afirma Tejedor. <\/p>\n\n<p>\u201cEn l\u2019\u00e0mbit catal\u00e0, la pobresa energ\u00e8tica \u00e9s cada cop m\u00e9s elevada\u201d, assenyala Sofia Recio. Amb aquesta app i amb l\u2019\u00fas de codi obert per a fer-la es vol tamb\u00e9 \u201cimpulsar que les administracions vegin la necessitat de tenir un servei similar com a Barcelona, Santa Coloma&#8230; Veure la import\u00e0ncia d\u2019aquest servei i fer-lo extensiu a nivell de ciutadania\u201d, afegeix. Aix\u00ed, la incorporaci\u00f3 d\u2019aquesta web app permetria establir una comunicaci\u00f3 m\u00e9s fluida entre les professionals i les persones usu\u00e0ries, facilitar l\u2019atenci\u00f3 per part de les professionals i una major transpar\u00e8ncia amb relaci\u00f3 als tr\u00e0mits i gestions per a la ciutadania.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>El projecte la Meva Energia est\u00e0 finan\u00e7at pel Fons Europeu Next Generation i pel Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia del Gobierno de Espa\u00f1a.<\/p>\n\n<p><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/3BtPMglUF2qiI2K6OiFgNeB418_RzMb4AePQfqyEn4xJnBHprK2CbE0fyTlDXEMMzNr3Zt8HEQYjbNzZ9Dd2eQTI9iH8nWFCaasWiK8Gx4g7cfoVPq7oa8pKOKT6UFNuV3sx7HYriLO-CEW_bj7Dh7I\" width=\"605\" height=\"49\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i BitGenoma, on ja van participar tamb\u00e9 les coordinadores dels&hellip;<\/p>\n","protected":false},"author":9,"featured_media":159891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3195,2296,2231],"tags":[],"class_list":["post-159893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusio-i-pobresa","category-internacional-ca","category-pobreza-energetica-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Meva Energia: L&#039;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma - ABD<\/title>\n<meta name=\"description\" content=\"Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Meva Energia: L&#039;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma - ABD\" \/>\n<meta property=\"og:description\" content=\"Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/\" \/>\n<meta property=\"og:site_name\" content=\"ABD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abd.ong\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T11:48:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T11:58:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abd.ong\/wp-content\/uploads\/2024\/04\/IMG_1831-3-1-e1714391353979.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Creixell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abd_ong\" \/>\n<meta name=\"twitter:site\" content=\"@abd_ong\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Creixell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/\"},\"author\":{\"name\":\"Maria Creixell\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/person\\\/d2e158b4173f683b3898e286f5b35a10\"},\"headline\":\"La Meva Energia: L&#8217;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma\",\"datePublished\":\"2024-04-29T11:48:30+00:00\",\"dateModified\":\"2024-04-29T11:58:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/\"},\"wordCount\":651,\"publisher\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_1831-3-1-e1714391353979.jpg\",\"articleSection\":[\"Inclusi\u00f3 i pobresa\",\"Internacional\",\"Pobreza energ\u00e9tica\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/\",\"url\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/\",\"name\":\"La Meva Energia: L'app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma - ABD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_1831-3-1-e1714391353979.jpg\",\"datePublished\":\"2024-04-29T11:48:30+00:00\",\"dateModified\":\"2024-04-29T11:58:30+00:00\",\"description\":\"Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_1831-3-1-e1714391353979.jpg\",\"contentUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_1831-3-1-e1714391353979.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/internacional-ca\\\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/abd.ong\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Meva Energia: L&#8217;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/abd.ong\\\/ca\\\/\",\"name\":\"ABD\",\"description\":\"Asociaci\u00f3n Bienestar y Desarrollo\",\"publisher\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abd.ong\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#organization\",\"name\":\"Associaci\u00f3 Benestar i Desenvolupament\",\"alternateName\":\"ABD\",\"url\":\"https:\\\/\\\/abd.ong\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Icona.png\",\"contentUrl\":\"https:\\\/\\\/abd.ong\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Icona.png\",\"width\":190,\"height\":187,\"caption\":\"Associaci\u00f3 Benestar i Desenvolupament\"},\"image\":{\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/abd.ong\",\"https:\\\/\\\/x.com\\\/abd_ong\",\"https:\\\/\\\/www.instagram.com\\\/abd_ong\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/abdong\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CANALABD\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/abd.ong\\\/ca\\\/#\\\/schema\\\/person\\\/d2e158b4173f683b3898e286f5b35a10\",\"name\":\"Maria Creixell\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Meva Energia: L'app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma - ABD","description":"Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/","og_locale":"ca_ES","og_type":"article","og_title":"La Meva Energia: L'app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma - ABD","og_description":"Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i","og_url":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/","og_site_name":"ABD","article_publisher":"https:\/\/www.facebook.com\/abd.ong","article_published_time":"2024-04-29T11:48:30+00:00","article_modified_time":"2024-04-29T11:58:30+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/abd.ong\/wp-content\/uploads\/2024\/04\/IMG_1831-3-1-e1714391353979.jpg","type":"image\/jpeg"}],"author":"Maria Creixell","twitter_card":"summary_large_image","twitter_creator":"@abd_ong","twitter_site":"@abd_ong","twitter_misc":{"Escrit per":"Maria Creixell","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#article","isPartOf":{"@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/"},"author":{"name":"Maria Creixell","@id":"https:\/\/abd.ong\/ca\/#\/schema\/person\/d2e158b4173f683b3898e286f5b35a10"},"headline":"La Meva Energia: L&#8217;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma","datePublished":"2024-04-29T11:48:30+00:00","dateModified":"2024-04-29T11:58:30+00:00","mainEntityOfPage":{"@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/"},"wordCount":651,"publisher":{"@id":"https:\/\/abd.ong\/ca\/#organization"},"image":{"@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#primaryimage"},"thumbnailUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2024\/04\/IMG_1831-3-1-e1714391353979.jpg","articleSection":["Inclusi\u00f3 i pobresa","Internacional","Pobreza energ\u00e9tica"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/","url":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/","name":"La Meva Energia: L'app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma - ABD","isPartOf":{"@id":"https:\/\/abd.ong\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#primaryimage"},"image":{"@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#primaryimage"},"thumbnailUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2024\/04\/IMG_1831-3-1-e1714391353979.jpg","datePublished":"2024-04-29T11:48:30+00:00","dateModified":"2024-04-29T11:58:30+00:00","description":"Despr\u00e9s d\u2019un proc\u00e9s de cocreaci\u00f3 entre les entitats s\u00f2cies del projecte, Associaci\u00f3 Benestar i Desenvolupament \u2013 Grup ABD, l\u2019Associaci\u00f3 Ecoserveis i","breadcrumb":{"@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#primaryimage","url":"https:\/\/abd.ong\/wp-content\/uploads\/2024\/04\/IMG_1831-3-1-e1714391353979.jpg","contentUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2024\/04\/IMG_1831-3-1-e1714391353979.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/abd.ong\/ca\/internacional-ca\/la-meva-energia-lapp-web-que-assessorara-sobre-consum-energetic-a-la-ciutadania-de-barcelona-comenca-a-prendre-forma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/abd.ong\/ca\/"},{"@type":"ListItem","position":2,"name":"La Meva Energia: L&#8217;app web que assessorar\u00e0 sobre consum energ\u00e8tic a la ciutadania de Barcelona comen\u00e7a a prendre forma"}]},{"@type":"WebSite","@id":"https:\/\/abd.ong\/ca\/#website","url":"https:\/\/abd.ong\/ca\/","name":"ABD","description":"Asociaci\u00f3n Bienestar y Desarrollo","publisher":{"@id":"https:\/\/abd.ong\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abd.ong\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/abd.ong\/ca\/#organization","name":"Associaci\u00f3 Benestar i Desenvolupament","alternateName":"ABD","url":"https:\/\/abd.ong\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/abd.ong\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/abd.ong\/wp-content\/uploads\/2023\/01\/Icona.png","contentUrl":"https:\/\/abd.ong\/wp-content\/uploads\/2023\/01\/Icona.png","width":190,"height":187,"caption":"Associaci\u00f3 Benestar i Desenvolupament"},"image":{"@id":"https:\/\/abd.ong\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abd.ong","https:\/\/x.com\/abd_ong","https:\/\/www.instagram.com\/abd_ong\/","https:\/\/www.linkedin.com\/company\/abdong","https:\/\/www.youtube.com\/user\/CANALABD"]},{"@type":"Person","@id":"https:\/\/abd.ong\/ca\/#\/schema\/person\/d2e158b4173f683b3898e286f5b35a10","name":"Maria Creixell"}]}},"_links":{"self":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts\/159893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/comments?post=159893"}],"version-history":[{"count":1,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts\/159893\/revisions"}],"predecessor-version":[{"id":159894,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/posts\/159893\/revisions\/159894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/media\/159891"}],"wp:attachment":[{"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/media?parent=159893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/categories?post=159893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abd.ong\/ca\/wp-json\/wp\/v2\/tags?post=159893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}